{"id":2715,"date":"2021-05-11T14:22:11","date_gmt":"2021-05-11T12:22:11","guid":{"rendered":"https:\/\/devstage.bix-consulting.com\/?p=2715"},"modified":"2023-06-16T11:50:51","modified_gmt":"2023-06-16T09:50:51","slug":"erweiterung-bestehendes-bw","status":"publish","type":"post","link":"https:\/\/www.bix-consulting.com\/en\/erweiterung-bestehendes-bw\/","title":{"rendered":"Extension of an existing business warehouse"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; disabled_on=&#8220;on|on|on&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||0px||false|false&#8220; disabled=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_row use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F4F4F4&#8243; border_radii=&#8220;off|20px|20px||&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|20px||20px|false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;]<\/p>\n<h4>Herausforderung<\/h4>\n<p style=\"text-align: justify;\">Ein in europaweit agierendes Unternehmen bietet Tankkarten f\u00fcr seine ca. 250.000 Gesch\u00e4ftskunden an. Das Gesch\u00e4ftsmodell beinhaltet f\u00fcr das Unternehmen ein hohes finanzielles Risiko, da es prozessbedingt in Vorleistung (Kostenabgang vor Zahlung des Endkunden) geht. Die H\u00f6he der Vorleistung betr\u00e4gt pro Monat einen 10-stelligen Betrag! Ziel muss es demnach sein, die Wahrscheinlichkeit eines Zahlungsausfalls zu minimieren.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_post_title title=&#8220;off&#8220; meta=&#8220;off&#8220; force_fullwidth=&#8220;off&#8220; image_width=&#8220;60%&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F4F4F4&#8243; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F4F4F4&#8243; custom_padding=&#8220;20px|20px|20px|20px|false|false&#8220; border_radii=&#8220;off|||20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;]<\/p>\n<h4>Unser L\u00f6sungsansatz<\/h4>\n<p style=\"text-align: justify;\">biX Consulting hat auf Basis von KI ein Modell entwickelt, welches die Problematik der Kundenbewertung deutlich optimiert. Im Rahmen von Big Data werden sekundenschnell interne sowie externe Daten zusammengef\u00fchrt, verarbeitet und daraus eine verl\u00e4ssliche Aussage zur Bonit\u00e4t des (Neu)-Kunden getroffen. Mit dieser L\u00f6sung wird die Wahrscheinlichkeit des Ausfallsrisikos elementar reduziert.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_row use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F4F4F4&#8243; border_radii=&#8220;on|20px|20px|20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|20px|0px|20px|false|false&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h4>Herausforderung<\/h4>\n<p style=\"text-align: justify;\">Das Monitoring von Ladeprozessen im Data Warehousing stellt h\u00e4ufig eine besondere Herausforderung da. Denn auch wenn alle Prozesse anscheinend fehlerlos durchlaufen wurden, bedeutet dies nicht, dass die Daten in der ben\u00f6tigten Qualit\u00e4t vorliegen. Gerade nicht offensichtlich auftretende Fehler machen eine regelm\u00e4\u00dfige quantitative und qualitative Pr\u00fcfung der Daten n\u00f6tig, die manuell und zeitaufwendig durchgef\u00fchrt werden muss.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_post_title title=&#8220;off&#8220; meta=&#8220;off&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; border_radii=&#8220;on|20px|20px|20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;RGBA(255,255,255,0)&#8220; custom_padding=&#8220;20px|20px|20px|20px|false|false&#8220; hover_enabled=&#8220;0&#8243; border_radii=&#8220;off|||20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h4>Unser L\u00f6sungsansatz<\/h4>\n<p style=\"text-align: justify;\">Auf Basis der Historie wird ein Modell erstellt, aus dem das Data Warehouse System lernt, wie sich durch die t\u00e4glichen Ladeprozesse \u00c4nderungen in den Datenbest\u00e4nden ergeben und in welchem Rahmen diese als normal anzusehen sind. Auf dieser Basis k\u00f6nnen dann Korridore mit Bezug auf Anzahl der \u00c4nderungen aber auch auf inhaltliche Elemente, wie beispielsweise Ausrei\u00dfer in Kennzahlen oder auch Summen bestimmter Aggregationsebenen, bestimmt werden. Werden diese Korridore dann \u00fcber- oder unterschritten, meldet dies das System und eine gezielte Fehleranalyse ist m\u00f6glich.<\/p>\n<p style=\"text-align: justify;\">Mit den biX AI Tools kann der L\u00f6sungsansatz vollst\u00e4ndig in Ihr SAP System integriert werden.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F4F4F4&#8243; border_radii=&#8220;on|20px|20px|20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|20px||20px|false|false&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h4>Ihr Nutzen<\/h4>\n<p style=\"text-align: justify;\"><span>Aufw\u00e4nde f\u00fcr das Monitoring k\u00f6nnen deutlich reduziert werden, da die regelm\u00e4\u00dfige \u00dcberwachung durch das System selbst erfolgt. Au\u00dferdem k\u00f6nnen Abweichungen sowohl quantitativer als auch qualitativer Aspekte fr\u00fcher erkannt und analysiert werden. Dies f\u00fchrt langfristig zu einer h\u00f6heren Gesamtqualit\u00e4t des Systems.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reduction of the monitoring effort through customer-specific extensions of the existing business warehouse<\/p>","protected":false},"author":6,"featured_media":2829,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_lmt_disableupdate":"","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"iawp_total_views":56,"footnotes":""},"categories":[32],"tags":[43,39,26,45,29,31,61,89,92,48,40,93,90,91,38,27,44,41,50,42,49,46,47],"class_list":["post-2715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-use-cases","tag-beratung","tag-big-data","tag-bix","tag-bix-beratung","tag-bix-consulting","tag-bix-sap","tag-bw","tag-bw-anwendungen","tag-bw-anwendungen-qs-funktionen","tag-consulting","tag-data-science","tag-erweiterung-bestehender-bw-anwendungen-um-qs-funktionen","tag-qs","tag-qs-funktionen","tag-ratingen","tag-sap","tag-sap-beratung","tag-sap-bw","tag-sap-consulting","tag-sap-hana","tag-sap-solutions","tag-service","tag-solution"],"modified_by":"admin","_links":{"self":[{"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/posts\/2715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/comments?post=2715"}],"version-history":[{"count":0,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/posts\/2715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/media\/2829"}],"wp:attachment":[{"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/media?parent=2715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/categories?post=2715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/tags?post=2715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}