{"id":2703,"date":"2021-05-11T14:17:24","date_gmt":"2021-05-11T12:17:24","guid":{"rendered":"https:\/\/devstage.bix-consulting.com\/?p=2703"},"modified":"2023-06-16T11:59:34","modified_gmt":"2023-06-16T09:59:34","slug":"optimierung-stammdatenqualitaet","status":"publish","type":"post","link":"https:\/\/www.bix-consulting.com\/en\/optimierung-stammdatenqualitaet\/","title":{"rendered":"Optimization of master data quality"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; disabled_on=&#8220;on|on|on&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||0px||false|false&#8220; disabled=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_row use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F4F4F4&#8243; border_radii=&#8220;off|20px|20px||&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|20px||20px|false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;]<\/p>\n<h4>Herausforderung<\/h4>\n<p style=\"text-align: justify;\">Ein in europaweit agierendes Unternehmen bietet Tankkarten f\u00fcr seine ca. 250.000 Gesch\u00e4ftskunden an. Das Gesch\u00e4ftsmodell beinhaltet f\u00fcr das Unternehmen ein hohes finanzielles Risiko, da es prozessbedingt in Vorleistung (Kostenabgang vor Zahlung des Endkunden) geht. Die H\u00f6he der Vorleistung betr\u00e4gt pro Monat einen 10-stelligen Betrag! Ziel muss es demnach sein, die Wahrscheinlichkeit eines Zahlungsausfalls zu minimieren.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_post_title title=&#8220;off&#8220; meta=&#8220;off&#8220; force_fullwidth=&#8220;off&#8220; image_width=&#8220;60%&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F4F4F4&#8243; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F4F4F4&#8243; custom_padding=&#8220;20px|20px|20px|20px|false|false&#8220; border_radii=&#8220;off|||20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;]<\/p>\n<h4>Unser L\u00f6sungsansatz<\/h4>\n<p style=\"text-align: justify;\">biX Consulting hat auf Basis von KI ein Modell entwickelt, welches die Problematik der Kundenbewertung deutlich optimiert. Im Rahmen von Big Data werden sekundenschnell interne sowie externe Daten zusammengef\u00fchrt, verarbeitet und daraus eine verl\u00e4ssliche Aussage zur Bonit\u00e4t des (Neu)-Kunden getroffen. Mit dieser L\u00f6sung wird die Wahrscheinlichkeit des Ausfallsrisikos elementar reduziert.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_row use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F4F4F4&#8243; border_radii=&#8220;on|20px|20px|20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|20px||20px|false|false&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h4>Herausforderung<\/h4>\n<p style=\"text-align: justify;\"><span>Manuell gepflegte Stammdaten weisen immer wieder schwerwiegende Qualit\u00e4tsm\u00e4ngel auf und verhindern weiterf\u00fchrende Analysen oder verf\u00e4lschen Analyseergebnisse, was schlimmstenfalls zu teuren Fehlentscheidungen f\u00fchren kann. H\u00e4ndische oder auch einfache statistische Verfahren erzeugen nicht die ben\u00f6tigte Qualit\u00e4t oder scheitern an rein quantitativen Grenzen.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_post_title title=&#8220;off&#8220; meta=&#8220;off&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; border_radii=&#8220;on|20px|20px|20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;RGBA(255,255,255,0)&#8220; custom_padding=&#8220;20px|20px|20px|20px|false|false&#8220; hover_enabled=&#8220;0&#8243; border_radii=&#8220;off|||20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h4>Unser L\u00f6sungsansatz<\/h4>\n<p style=\"text-align: justify;\"><span>Basierend auf der Nutzung der Stammdaten in den Unternehmensprozessen wird ein neuronales Netz trainiert, das es erlaubt eine digitale Landkarte \u00e4hnlicher Stammdatenauspr\u00e4gungen zu erzeugen. Basierend auf dieser Landkarte ist es m\u00f6glich, fehlende Stammdaten automatisch zu erzeugen oder wahrscheinlich falsch gepflegte Stammdaten zu identifizieren und manuell oder automatisch\u00a0 zu korrigieren.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_image src=&#8220;https:\/\/www.bix-consulting.com\/wp-content\/uploads\/2021\/05\/Optimierung-Stammdatenqulitaet.png&#8220; title_text=&#8220;Optimierung-Stammdatenqulit\u00e4t&#8220; show_bottom_space=&#8220;off&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|20px||20px|false|false&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220; sticky_enabled=&#8220;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|20px||20px|false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;]<\/p>\n<p><span>Mit den biX AI Tools kann der L\u00f6sungsansatz vollst\u00e4ndig in Ihr SAP System integriert werden.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F4F4F4&#8243; border_radii=&#8220;on|20px|20px|20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|20px||20px|false|false&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;et_body_layout&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h4>Ihr Nutzen<\/h4>\n<p style=\"text-align: justify;\"><span>Die Stammdatenqualit\u00e4t wird signifikant verbessert und kontinuierlich ohne zus\u00e4tzliche manuelle Aufw\u00e4nde auf diesem hohen Niveau gehalten. Somit werden weiterf\u00fchrende Analysen m\u00f6glich und darauf basierende Fehlentscheidungen zuk\u00fcnftig minimiert.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Training of a neural network for significant improvement and sustainability of master data quality without additional manual effort<\/p>","protected":false},"author":6,"featured_media":2826,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_lmt_disableupdate":"","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"iawp_total_views":17,"footnotes":""},"categories":[32],"tags":[43,39,26,45,29,31,48,34,40,114,109,111,112,113,110,38,27,44,41,50,42,49,46,47,108,107,36],"class_list":["post-2703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-use-cases","tag-beratung","tag-big-data","tag-bix","tag-bix-beratung","tag-bix-consulting","tag-bix-sap","tag-consulting","tag-data","tag-data-science","tag-daten","tag-datenqualitaet","tag-optimieren","tag-optimierung","tag-optimierung-stammdaten","tag-qualitaet","tag-ratingen","tag-sap","tag-sap-beratung","tag-sap-bw","tag-sap-consulting","tag-sap-hana","tag-sap-solutions","tag-service","tag-solution","tag-stamdatenqualitaet","tag-stammdaten","tag-strategie"],"modified_by":"admin","_links":{"self":[{"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/posts\/2703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/comments?post=2703"}],"version-history":[{"count":0,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/posts\/2703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/media\/2826"}],"wp:attachment":[{"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/media?parent=2703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/categories?post=2703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/tags?post=2703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}