{"id":2372,"date":"2020-12-08T00:00:34","date_gmt":"2020-12-07T23:00:34","guid":{"rendered":"https:\/\/devstage.bix-consulting.com\/?p=2372"},"modified":"2023-06-22T14:32:22","modified_gmt":"2023-06-22T12:32:22","slug":"sap-analytics-cloud-live-zugriff-auf-externe-daten","status":"publish","type":"post","link":"https:\/\/www.bix-consulting.com\/en\/sap-analytics-cloud-live-zugriff-auf-externe-daten\/","title":{"rendered":"SAP Analytics Cloud - Live access to external data"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; disabled_on=&#8220;on|on|on&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||0px||false|false&#8220; disabled=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_row use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F4F4F4&#8243; border_radii=&#8220;off|20px|20px||&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|20px||20px|false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<h4>Herausforderung<\/h4>\n<p style=\"text-align: justify;\">Ein in europaweit agierendes Unternehmen bietet Tankkarten f\u00fcr seine ca. 250.000 Gesch\u00e4ftskunden an. Das Gesch\u00e4ftsmodell beinhaltet f\u00fcr das Unternehmen ein hohes finanzielles Risiko, da es prozessbedingt in Vorleistung (Kostenabgang vor Zahlung des Endkunden) geht. Die H\u00f6he der Vorleistung betr\u00e4gt pro Monat einen 10-stelligen Betrag! Ziel muss es demnach sein, die Wahrscheinlichkeit eines Zahlungsausfalls zu minimieren.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_post_title title=&#8220;off&#8220; meta=&#8220;off&#8220; force_fullwidth=&#8220;off&#8220; image_width=&#8220;60%&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F4F4F4&#8243; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F4F4F4&#8243; custom_padding=&#8220;20px|20px|20px|20px|false|false&#8220; border_radii=&#8220;off|||20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<h4>Unser L\u00f6sungsansatz<\/h4>\n<p style=\"text-align: justify;\">biX Consulting hat auf Basis von KI ein Modell entwickelt, welches die Problematik der Kundenbewertung deutlich optimiert. Im Rahmen von Big Data werden sekundenschnell interne sowie externe Daten zusammengef\u00fchrt, verarbeitet und daraus eine verl\u00e4ssliche Aussage zur Bonit\u00e4t des (Neu)-Kunden getroffen. Mit dieser L\u00f6sung wird die Wahrscheinlichkeit des Ausfallsrisikos elementar reduziert.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_row use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F4F4F4&#8243; border_radii=&#8220;on|20px|20px|20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|20px||20px|false|false&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p style=\"text-align: justify;\">SAP Analytics Cloud (SAC) ist das Standard Werkzeug, wenn es um das Analysieren von Daten, insbesondere in der SAP-Welt, geht. Oft ist es erforderlich zus\u00e4tzlich externe Datenquellen f\u00fcr in Analysen einzubeziehen und deren Daten m\u00f6glichst in Echtzeit zu verarbeiten. Dies erweitert das Analysespektrum und kann gegebenenfalls neue Erkenntnisse f\u00fcr anstehende Entscheidungen liefern, ist in vielen F\u00e4llen aber eine technische Herausforderung.<\/p>\n<p style=\"text-align: justify;\">Mit Verbindung der SAP Analytics Cloud zum Harmonization Layer von denodo bietet biX Consulting eine L\u00f6sung an, die die M\u00f6glichkeit zur Integration heterogener Datenquellen deutlich erweitert. Insbesondere wird hier auf die Beibehaltung der Data Governance, also Nutzung des bestehenden Rechtemanagements aus dem SAP BW, keine Persistierung von externen Daten in der SAP Cloud, sowie die M\u00f6glichkeit f\u00fcr Multi-User-Zugriffe, Wert gelegt.<\/p>\n<h4 style=\"text-align: justify;\">SAC und R-Server<\/h4>\n<p style=\"text-align: justify;\">Die SAP Analytics Cloud (SAC) bietet die M\u00f6glichkeit, einen R-Server einzubinden und mit eigenen Modulen zu erweitern. Aus dem R-Server heraus ist es wiederum m\u00f6glich, auf andere Systeme zuzugreifen. Dieser Zugriff wird mittels geeigneter Treiber wie zum Beispiel JDBC realisiert.<\/p>\n<p style=\"text-align: justify;\">Der R-Server \u00fcbernimmt in diesem Szenario eine Art Hub-Funktion. So ist es zum Beispiel m\u00f6glich, Datenfilter aus der SAP Analytics Cloud \u00fcber den R-Server an die nachgelagerten Systeme zu \u00fcbergeben. Daten \u00fcber statistische Methoden vorzuberechnen oder komplexe Visualisierung zu realisieren ist ebenfalls m\u00f6glich.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_image src=&#8220;https:\/\/www.bix-consulting.com\/wp-content\/uploads\/2023\/06\/R-Server_Denodo_SAC.png&#8220; title_text=&#8220;R-Server_Denodo_SAC&#8220; show_bottom_space=&#8220;off&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|20px||20px|false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;RGBA(255,255,255,0)&#8220; custom_padding=&#8220;20px|20px|20px|20px|false|false&#8220; border_radii=&#8220;off|||20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<h4>R-Server und denodo<\/h4>\n<p style=\"text-align: justify;\">Die denodo Datenvirtualisierungsplattform \u00fcbernimmt eine zentrale Rolle. Sie steuert den Zugriff auf heterogene und verteilte Systeme und erm\u00f6glicht somit einen harmonisierten Zugriff des R-Servers auf die Daten. So wandelt denodo zum Beispiel externe Web-Services in Views um, die dann mit einfachen SQLWerkzeugen aus dem R-Server herausgelesen werden k\u00f6nnen. Technisch sind RServer und denodo \u00fcber eine LAN-Verbindung oder \u00fcber das Internet verbunden.<\/p>\n<h6 style=\"text-align: justify;\">Datenlieferant f\u00fcr den SAC-Live-Zugriff<\/h6>\n<p style=\"text-align: justify;\">Um den Zugriff auf die externen Daten mit einer SAC Live Data Connection zu erm\u00f6glichen, werden die Daten vom R-Server aus in das SAP Business Warehouse geschrieben. Hierf\u00fcr werden SAP BW-seitig Advanced Data Store Objects (aDSO) zum Persistieren der Daten, Composite Provider und Queries zur Visualisierung der Reports und f\u00fcr den Live-Zugriff aus der SAC genutzt.<\/p>\n<p style=\"text-align: justify;\">\u00dcber den Live-Zugriff ist es m\u00f6glich, Queries im SAP Business Warehouse (BW) in Echtzeit, also ohne zus\u00e4tzliche Persistenz in der Cloud, auszuf\u00fchren. Bei \u00c4nderung von Daten im SAP BW werden somit auch die Anzeigeelemente der SAC aufgefrischt.<\/p>\n<p style=\"text-align: justify;\">Multi-User Zugriffe werden durch Filterung der Daten nach anfragenden Benutzern erm\u00f6glicht und das Berechtigungssystem des SAP BW verwendet.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_image src=&#8220;https:\/\/www.bix-consulting.com\/wp-content\/uploads\/2023\/06\/Denodo_Showcase.png&#8220; title_text=&#8220;Denodo_Showcase&#8220; show_bottom_space=&#8220;off&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|20px||20px|false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_image][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|20px||20px|false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<p>Erweiterung der Analysem\u00f6glichkeiten in der SAC durch Integration externer Daten zur Laufzeit<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;10px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;RGBA(255,255,255,0)&#8220; custom_padding=&#8220;20px|20px|20px|20px|false|false&#8220; border_radii=&#8220;off|||20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<h4>Technische Anforderungen<\/h4>\n<ul style=\"margin-left:1.5em\">\n<li>R Server mit Verbindung SAC und denodo<\/li>\n<li>R Server Module f\u00fcr persistente Daten<\/li>\n<li>R Server Module f\u00fcr Schnittstellen-Interaktionen<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;15px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F4F4F4&#8243; border_radii=&#8220;on|20px|20px|20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|20px||20px|false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<h4>Vorteile<\/h4>\n<p style=\"text-align: justify;\">Die von biX Consulting entwickelte L\u00f6sung bietet einen zentralen Zugriffspunkt auf externe und interne Daten mit Hilfe der denodo-Infrastruktur. Es ist kein Upload von Daten in die SAP-Cloud erforderlich. Die zu integrierenden Daten k\u00f6nnen vom Benutzer in der SAC angefordert werden. Die Persistierung der externen und der mit Hilfe der denodo-Plattform harmonisierten Daten erfolgt im SAP BW, von wo aus sie in die SAC gelesen und visualisiert werden k\u00f6nnen. Es sind Multi-UserZugriffe m\u00f6glich. F\u00fcr die SAC Live-Verbindung sind keine weiteren Softwarelizenzen erforderlich.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_post_title title=&#8220;off&#8220; meta=&#8220;off&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; border_radii=&#8220;on|20px|20px|20px|20px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Development of a central access point for internal and external data using the Denodo infrastructure<\/p>","protected":false},"author":6,"featured_media":3641,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_lmt_disableupdate":"","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"iawp_total_views":55,"footnotes":""},"categories":[32],"tags":[43,39,26,45,29,31,73,77,48,128,40,143,142,80,130,129,38,24,27,127,44,41,131,50,42,49,46,47,144],"class_list":["post-2372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-use-cases","tag-beratung","tag-big-data","tag-bix","tag-bix-beratung","tag-bix-consulting","tag-bix-sap","tag-cloud","tag-cloud-data","tag-consulting","tag-content","tag-data-science","tag-externe-daten","tag-live-zugriff","tag-next-level-analytics-cloud-data-platform","tag-planung","tag-planungscontent","tag-ratingen","tag-sac","tag-sap","tag-sap-analyitics-cloud","tag-sap-beratung","tag-sap-bw","tag-sap-cloud","tag-sap-consulting","tag-sap-hana","tag-sap-solutions","tag-service","tag-solution","tag-zugriff-auf-daten"],"modified_by":"admin","_links":{"self":[{"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/posts\/2372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/comments?post=2372"}],"version-history":[{"count":0,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/posts\/2372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/media\/3641"}],"wp:attachment":[{"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/media?parent=2372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/categories?post=2372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bix-consulting.com\/en\/wp-json\/wp\/v2\/tags?post=2372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}